{"id":2530,"date":"2024-12-19T14:28:23","date_gmt":"2024-12-19T13:28:23","guid":{"rendered":"https:\/\/museum-ravensburger.de\/groups\/"},"modified":"2025-09-25T15:19:16","modified_gmt":"2025-09-25T13:19:16","slug":"groups","status":"publish","type":"page","link":"https:\/\/museum-ravensburger.de\/en\/groups\/","title":{"rendered":"Groups"},"content":{"rendered":"<section id=\"acf-block-6764212f3723a\" class=\"header-text-image relative overflow-hidden max-md:mt-6 bg-bg-grey text-text-default dark:!text-light dark:!bg-dark\">\n    <div class=\"max-w-screen-fhd mx-auto\">\n        <div class=\"mx-auto md:px-lg  xl:flex flex-row-reverse xl:pl-32\">\n                            <div class=\"header-bg xl:h-[65vh] xl:max-h-[1000px] xl:w-1\/2 overflow-hidden xl:py-12\"> <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/01\/group.jpg?fit=1080%2C1080&amp;ssl=1\" class=\"object-cover z-0 h-full w-full object-center\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/01\/group.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/01\/group.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/01\/group.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/01\/group.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/01\/group.jpg?resize=768%2C768&amp;ssl=1 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-attachment-id=\"1997\" data-permalink=\"https:\/\/museum-ravensburger.de\/en\/group-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/01\/group.jpg?fit=1080%2C1080&amp;ssl=1\" data-orig-size=\"1080,1080\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"group\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/01\/group.jpg?fit=1024%2C1024&amp;ssl=1\" \/>                <\/div>             <div class=\"max-md:px-md max-sm:px-sm max-xs:px-xs xl:px-0 relative py-10 md:py-16 xl:py-0 xl:h-[65vh] mx-auto max-h-[1000px] w-full xl:w-1\/2 flex flex-col z-10 justify-center align-left xl:pr-32\">\n                                    <h1 class=\"w-full font-bold typo-h1-header \">Discovering Together Is the Best Way! <\/h1>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<section class=\"text-image-module bg-bg-default text-text-default\">\n    <div class=\"dark:!text-white dark:!bg-dark\">\n        <div class=\"max-w-screen-2xl spacing-px spacing-py mx-auto\">\n            <div class=\"content-top max-w-3xl align-left \">\n                            <\/div>\n            <div class=\"grid grid-cols-1 2xl:gap-offsetMd gap-md \">\n                <div class=\"text-image-single flex max-lg:flex-col\">\n      <div class=\"image-box lg:w-1\/2 \">\n        <div class=\"image-box-img overflow-hidden aspect-square \">\n          <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/DSC08654.jpg?fit=768%2C512&amp;ssl=1\" class=\"h-full w-full object-cover z-0 transform scale-105 transition duration-300\" alt=\"Vereine, Firmen und private Gruppen\" srcset=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/DSC08654.jpg?w=6799&amp;ssl=1 6799w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/DSC08654.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/DSC08654.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/DSC08654.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/DSC08654.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/DSC08654.jpg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/DSC08654.jpg?resize=1900%2C1267&amp;ssl=1 1900w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/DSC08654.jpg?resize=1240%2C827&amp;ssl=1 1240w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/DSC08654.jpg?w=3000&amp;ssl=1 3000w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-attachment-id=\"2050\" data-permalink=\"https:\/\/museum-ravensburger.de\/en\/groups\/dsc08654-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/DSC08654.jpg?fit=6799%2C4533&amp;ssl=1\" data-orig-size=\"6799,4533\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;ILCE-7M4&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1739058448&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;46.1&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"DSC08654\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/DSC08654.jpg?fit=1024%2C683&amp;ssl=1\" \/>        <\/div>\n      <\/div>\n      <div class=\"content-box lg:w-1\/2 flex flex-col justify-center bg-bg-transparent \">\n        <div class=\"content-box-inner  image-side-left \">\n          <h2 class='headline-element align-left typo-h3 font-bold'>Associations, Companies, and Private Groups <\/h2><p class='text-element align-left typo-body mt-xs'><p>Whether you&#8217;re visiting as a club, company, or private group \u2013 at Museum Ravensburger, you&#8217;ll gain exciting insights into the world of games, books, and puzzles.<br \/>With our special group offers, your visit becomes an inspiring shared experience full of discoveries and lasting memories. <\/p>\n<\/p>        <a  target=\"_self\" href=\"https:\/\/museum-ravensburger.de\/en\/groups\/associations-companies-and-private-groups\/\" class=\"btn-primary mt-sm with-icon\">\n            Get together!                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M12.175 9H0V7H12.175L6.575 1.4L8 0L16 8L8 16L6.575 14.6L12.175 9Z\" fill=\"white\"\/>\n                <\/svg>\n                    <\/a>\n                <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"text-image-single flex max-lg:flex-col\">\n      <div class=\"image-box lg:w-1\/2 lg:order-1\">\n        <div class=\"image-box-img overflow-hidden aspect-square \">\n          <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK09234.jpg?fit=768%2C432&amp;ssl=1\" class=\"h-full w-full object-cover z-0 transform scale-105 transition duration-300\" alt=\"Kinderg\u00e4rten und Schulklassen im Museum Ravensburger\" srcset=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK09234.jpg?w=3936&amp;ssl=1 3936w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK09234.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK09234.jpg?resize=1024%2C577&amp;ssl=1 1024w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK09234.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK09234.jpg?resize=1536%2C865&amp;ssl=1 1536w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK09234.jpg?resize=2048%2C1153&amp;ssl=1 2048w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK09234.jpg?resize=1900%2C1070&amp;ssl=1 1900w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK09234.jpg?resize=1240%2C698&amp;ssl=1 1240w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK09234.jpg?w=3000&amp;ssl=1 3000w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-attachment-id=\"2049\" data-permalink=\"https:\/\/museum-ravensburger.de\/en\/groups\/wrk09234-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK09234.jpg?fit=3936%2C2216&amp;ssl=1\" data-orig-size=\"3936,2216\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WRK09234\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK09234.jpg?fit=1024%2C577&amp;ssl=1\" \/>        <\/div>\n      <\/div>\n      <div class=\"content-box lg:w-1\/2 flex flex-col justify-center bg-bg-transparent \">\n        <div class=\"content-box-inner  image-side-right \">\n          <h2 class='headline-element align-left typo-h3 font-bold'>Kindergartens and School Classes<\/h2><p class='text-element align-left typo-body mt-xs'><p><span style=\"font-weight: 400;\">At Museum Ravensburger, children embark on an exciting journey behind the scenes of the world of games, books, and puzzles.<br \/>With our tailored offers for kindergartens and school classes, the museum visit becomes an unforgettable experience full of curiosity, creativity, and hands-on fun. <\/span><\/p>\n<\/p>        <a  target=\"_self\" href=\"https:\/\/museum-ravensburger.de\/en\/groups\/kindergartens-school-classes\/\" class=\"btn-primary mt-sm with-icon\">\n            Plan their field day!                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M12.175 9H0V7H12.175L6.575 1.4L8 0L16 8L8 16L6.575 14.6L12.175 9Z\" fill=\"white\"\/>\n                <\/svg>\n                    <\/a>\n                <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"text-image-single flex max-lg:flex-col\">\n      <div class=\"image-box lg:w-1\/2 \">\n        <div class=\"image-box-img overflow-hidden aspect-square \">\n          <img loading=\"lazy\" decoding=\"async\" width=\"515\" height=\"515\" src=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2024\/12\/Teaser_MR_515x515px_digitale_Fuehrung.webp?fit=515%2C515&amp;ssl=1\" class=\"h-full w-full object-cover z-0 transform scale-105 transition duration-300\" alt=\"Lauschtour-App mit dem eigenen Smartphone\" srcset=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2024\/12\/Teaser_MR_515x515px_digitale_Fuehrung.webp?w=515&amp;ssl=1 515w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2024\/12\/Teaser_MR_515x515px_digitale_Fuehrung.webp?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2024\/12\/Teaser_MR_515x515px_digitale_Fuehrung.webp?resize=150%2C150&amp;ssl=1 150w\" sizes=\"(max-width: 515px) 100vw, 515px\" data-attachment-id=\"1865\" data-permalink=\"https:\/\/museum-ravensburger.de\/en\/groups\/teaser_mr_515x515px_digitale_fuehrung-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2024\/12\/Teaser_MR_515x515px_digitale_Fuehrung.webp?fit=515%2C515&amp;ssl=1\" data-orig-size=\"515,515\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Teaser_MR_515x515px_digitale_Fu?hrung\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2024\/12\/Teaser_MR_515x515px_digitale_Fuehrung.webp?fit=515%2C515&amp;ssl=1\" \/>        <\/div>\n      <\/div>\n      <div class=\"content-box lg:w-1\/2 flex flex-col justify-center bg-bg-transparent \">\n        <div class=\"content-box-inner  image-side-left \">\n          <h2 class='headline-element align-left typo-h3 font-bold'>On a Journey of Discovery!<\/h2><p class='text-element align-left typo-body mt-xs'><p>Explore the exhibition with the Lauschtour app on your own smartphone.<br \/>If you prefer reading, you\u2019ll find the digital guide in German, English, French, and Italian right here on our website. Additionally, the museum offers a free public guided tour on the last Sunday of each month, where visitors gain exclusive insights into the history of Ravensburger \u2013 told in a lively and engaging way.  <\/p>\n<\/p>        <a  target=\"_self\" href=\"https:\/\/museum-ravensburger.de\/en\/services\/guided-tours\/\" class=\"btn-primary mt-sm with-icon\">\n            Learn more                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M12.175 9H0V7H12.175L6.575 1.4L8 0L16 8L8 16L6.575 14.6L12.175 9Z\" fill=\"white\"\/>\n                <\/svg>\n                    <\/a>\n                <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"text-image-single flex max-lg:flex-col\">\n      <div class=\"image-box lg:w-1\/2 lg:order-1\">\n        <div class=\"image-box-img overflow-hidden aspect-square \">\n          <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK08983.jpg?fit=768%2C432&amp;ssl=1\" class=\"h-full w-full object-cover z-0 transform scale-105 transition duration-300\" alt=\"Kindergeburtstag im Museuem Ravensburg\" srcset=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK08983.jpg?w=3936&amp;ssl=1 3936w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK08983.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK08983.jpg?resize=1024%2C577&amp;ssl=1 1024w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK08983.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK08983.jpg?resize=1536%2C865&amp;ssl=1 1536w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK08983.jpg?resize=2048%2C1153&amp;ssl=1 2048w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK08983.jpg?resize=1900%2C1070&amp;ssl=1 1900w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK08983.jpg?resize=1240%2C698&amp;ssl=1 1240w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK08983.jpg?w=3000&amp;ssl=1 3000w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-attachment-id=\"2032\" data-permalink=\"https:\/\/museum-ravensburger.de\/en\/services\/wrk08983-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK08983.jpg?fit=3936%2C2216&amp;ssl=1\" data-orig-size=\"3936,2216\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Ravensburger Spieleland Kindergeburtstag\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/WRK08983.jpg?fit=1024%2C577&amp;ssl=1\" \/>        <\/div>\n      <\/div>\n      <div class=\"content-box lg:w-1\/2 flex flex-col justify-center bg-bg-transparent \">\n        <div class=\"content-box-inner  image-side-right \">\n          <h2 class='headline-element align-left typo-h3 font-bold'>Children\u2019s Birthday at the Museum?<\/h2><p class='text-element align-left typo-body mt-xs'><p>Absolutely! Young explorers celebrate their big day here with games, fun, and exciting behind-the-scenes insights into the Ravensburger brand.<br \/>A lovingly designed program ensures bright eyes and lasting memories. <\/p>\n<\/p>        <a  target=\"_self\" href=\"https:\/\/museum-ravensburger.de\/en\/services\/birthday-party\/\" class=\"btn-primary mt-sm with-icon\">\n            Let\u2019s celebrate!                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M12.175 9H0V7H12.175L6.575 1.4L8 0L16 8L8 16L6.575 14.6L12.175 9Z\" fill=\"white\"\/>\n                <\/svg>\n                    <\/a>\n                <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"text-image-single flex max-lg:flex-col\">\n      <div class=\"image-box lg:w-1\/2 \">\n        <div class=\"image-box-img overflow-hidden aspect-square \">\n          <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/IMG_0850.jpg?fit=768%2C512&amp;ssl=1\" class=\"h-full w-full object-cover z-0 transform scale-105 transition duration-300\" alt=\"Ravensburger Angebot Heiraten\" srcset=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/IMG_0850.jpg?w=1500&amp;ssl=1 1500w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/IMG_0850.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/IMG_0850.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/IMG_0850.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/IMG_0850.jpg?resize=1240%2C827&amp;ssl=1 1240w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-attachment-id=\"2035\" data-permalink=\"https:\/\/museum-ravensburger.de\/en\/services\/wedding\/kaisers-hochzeit-2-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/IMG_0850.jpg?fit=1500%2C1000&amp;ssl=1\" data-orig-size=\"1500,1000\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5&quot;,&quot;credit&quot;:&quot;kaiser&quot;,&quot;camera&quot;:&quot;Canon EOS 6D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1629469796&quot;,&quot;copyright&quot;:&quot;\\u00a9 2023 kaiser, all rights reserved.&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;3200&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;Kaiser&#039;s Hochzeit&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Kaiser&amp;#8217;s Hochzeit\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2025\/08\/IMG_0850.jpg?fit=1024%2C683&amp;ssl=1\" \/>        <\/div>\n      <\/div>\n      <div class=\"content-box lg:w-1\/2 flex flex-col justify-center bg-bg-transparent \">\n        <div class=\"content-box-inner  image-side-left \">\n          <h2 class='headline-element align-left typo-h3 font-bold'>Playfully Entering the Bond of Marriage<\/h2><p class='text-element align-left typo-body mt-xs'><p>Weddings at the museum take place in a truly special setting:<br \/>In a stylish atmosphere with a touch of nostalgia, the most beautiful day of your life becomes an extraordinary experience \u2013 surrounded by games, books, and puzzles from childhood.<\/p>\n<\/p>        <a  target=\"_self\" href=\"https:\/\/museum-ravensburger.de\/en\/services\/wedding\/\" class=\"btn-primary mt-sm with-icon\">\n            Let\u2019s get married!                            <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M12.175 9H0V7H12.175L6.575 1.4L8 0L16 8L8 16L6.575 14.6L12.175 9Z\" fill=\"white\"\/>\n                <\/svg>\n                    <\/a>\n                <\/div>\n      <\/div>\n    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":131695058,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2530","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Groups - Museum Ravensburger<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/museum-ravensburger.de\/en\/groups\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Groups - Museum Ravensburger\" \/>\n<meta property=\"og:url\" content=\"https:\/\/museum-ravensburger.de\/en\/groups\/\" \/>\n<meta property=\"og:site_name\" content=\"Museum Ravensburger\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-25T13:19:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/museum-ravensburger.de\/en\/groups\/\",\"url\":\"https:\/\/museum-ravensburger.de\/en\/groups\/\",\"name\":\"Groups - Museum Ravensburger\",\"isPartOf\":{\"@id\":\"https:\/\/museum-ravensburger.de\/en\/#website\"},\"datePublished\":\"2024-12-19T13:28:23+00:00\",\"dateModified\":\"2025-09-25T13:19:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/museum-ravensburger.de\/en\/groups\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/museum-ravensburger.de\/en\/groups\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/museum-ravensburger.de\/en\/groups\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/museum-ravensburger.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Groups\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/museum-ravensburger.de\/en\/#website\",\"url\":\"https:\/\/museum-ravensburger.de\/en\/\",\"name\":\"Museum Ravensburger\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/museum-ravensburger.de\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/museum-ravensburger.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/museum-ravensburger.de\/en\/#organization\",\"name\":\"Museum Ravensburger\",\"url\":\"https:\/\/museum-ravensburger.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/museum-ravensburger.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2024\/12\/logo.png?fit=276%2C273&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2024\/12\/logo.png?fit=276%2C273&ssl=1\",\"width\":276,\"height\":273,\"caption\":\"Museum Ravensburger\"},\"image\":{\"@id\":\"https:\/\/museum-ravensburger.de\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Groups - Museum Ravensburger","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/museum-ravensburger.de\/en\/groups\/","og_locale":"en_US","og_type":"article","og_title":"Groups - Museum Ravensburger","og_url":"https:\/\/museum-ravensburger.de\/en\/groups\/","og_site_name":"Museum Ravensburger","article_modified_time":"2025-09-25T13:19:16+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/museum-ravensburger.de\/en\/groups\/","url":"https:\/\/museum-ravensburger.de\/en\/groups\/","name":"Groups - Museum Ravensburger","isPartOf":{"@id":"https:\/\/museum-ravensburger.de\/en\/#website"},"datePublished":"2024-12-19T13:28:23+00:00","dateModified":"2025-09-25T13:19:16+00:00","breadcrumb":{"@id":"https:\/\/museum-ravensburger.de\/en\/groups\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/museum-ravensburger.de\/en\/groups\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/museum-ravensburger.de\/en\/groups\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/museum-ravensburger.de\/en\/"},{"@type":"ListItem","position":2,"name":"Groups"}]},{"@type":"WebSite","@id":"https:\/\/museum-ravensburger.de\/en\/#website","url":"https:\/\/museum-ravensburger.de\/en\/","name":"Museum Ravensburger","description":"","publisher":{"@id":"https:\/\/museum-ravensburger.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museum-ravensburger.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/museum-ravensburger.de\/en\/#organization","name":"Museum Ravensburger","url":"https:\/\/museum-ravensburger.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/museum-ravensburger.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2024\/12\/logo.png?fit=276%2C273&ssl=1","contentUrl":"https:\/\/i0.wp.com\/museum-ravensburger.de\/wp-content\/uploads\/2024\/12\/logo.png?fit=276%2C273&ssl=1","width":276,"height":273,"caption":"Museum Ravensburger"},"image":{"@id":"https:\/\/museum-ravensburger.de\/en\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PgduLP-EO","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/museum-ravensburger.de\/en\/wp-json\/wp\/v2\/pages\/2530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museum-ravensburger.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/museum-ravensburger.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/museum-ravensburger.de\/en\/wp-json\/wp\/v2\/users\/131695058"}],"replies":[{"embeddable":true,"href":"https:\/\/museum-ravensburger.de\/en\/wp-json\/wp\/v2\/comments?post=2530"}],"version-history":[{"count":3,"href":"https:\/\/museum-ravensburger.de\/en\/wp-json\/wp\/v2\/pages\/2530\/revisions"}],"predecessor-version":[{"id":2695,"href":"https:\/\/museum-ravensburger.de\/en\/wp-json\/wp\/v2\/pages\/2530\/revisions\/2695"}],"wp:attachment":[{"href":"https:\/\/museum-ravensburger.de\/en\/wp-json\/wp\/v2\/media?parent=2530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}